{"id":2578,"count":1,"description":"","link":"https:\/\/ripperkon.de\/en\/tag\/central-point\/","name":"central point","slug":"central-point","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ripperkon.de\/en\/tag\/central-point\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2578\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tag\\\/central-point\\\/#listItem\",\"name\":\"central point\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tag\\\/central-point\\\/#listItem\",\"position\":2,\"name\":\"central point\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2578\\\/#collectionpage\",\"url\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2578\\\/\",\"name\":\"central point | Ripperkon\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/2578\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#organization\",\"name\":\"Ripperkon\",\"description\":\"Taktische Ausr\\u00fcstung im Fokus\",\"url\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ripperkon\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCA_0ltEzFO1OsSYo5_PA75A\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/\",\"name\":\"Ripperkon\",\"description\":\"Taktische Ausr\\u00fcstung im Fokus\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"central point | Ripperkon","description":"","canonical_url":"https:\/\/ripperkon.de\/en\/tag\/central-point\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/tags\/2578\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/ripperkon.de\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tag\/central-point\/#listItem","name":"central point"}},{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tag\/central-point\/#listItem","position":2,"name":"central point","previousItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/tags\/2578\/#collectionpage","url":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/tags\/2578\/","name":"central point | Ripperkon","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ripperkon.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/tags\/2578\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/ripperkon.de\/en\/#organization","name":"Ripperkon","description":"Taktische Ausr\u00fcstung im Fokus","url":"https:\/\/ripperkon.de\/en\/","sameAs":["https:\/\/www.instagram.com\/ripperkon\/","https:\/\/www.youtube.com\/channel\/UCA_0ltEzFO1OsSYo5_PA75A"]},{"@type":"WebSite","@id":"https:\/\/ripperkon.de\/en\/#website","url":"https:\/\/ripperkon.de\/en\/","name":"Ripperkon","description":"Taktische Ausr\u00fcstung im Fokus","inLanguage":"en-US","publisher":{"@id":"https:\/\/ripperkon.de\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ripperkon.de\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tcentral point\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ripperkon.de\/en\/"},{"label":"central point","link":"https:\/\/ripperkon.de\/en\/tag\/central-point\/"}],"_links":{"self":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/tags\/2578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/posts?tags=2578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}