{"id":18602,"date":"2012-05-16T20:11:17","date_gmt":"2012-05-16T20:11:17","guid":{"rendered":"https:\/\/ripperkon.de\/ca-g3-dmr\/"},"modified":"2012-05-16T20:11:17","modified_gmt":"2012-05-16T20:11:17","slug":"ca-g3-dmr","status":"publish","type":"page","link":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ca-g3-dmr\/","title":{"rendered":"Classic Army G3 DMR"},"content":{"rendered":"<p><strong>VERKAUFT<\/strong>, weil es mir zu viel Geld frisst und ich es zur Zeit nicht wirklich einbeziehen kann.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14837\" src=\"http:\/\/ripperkon.de\/wp-content\/uploads\/IMG_5811.jpg\" alt=\"IMG_5811\" width=\"1422\" height=\"560\" srcset=\"https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_5811.jpg 1422w, https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_5811-300x118.jpg 300w, https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_5811-1024x403.jpg 1024w\" sizes=\"auto, (max-width: 1422px) 100vw, 1422px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14835\" src=\"http:\/\/ripperkon.de\/wp-content\/uploads\/IMG_5813.jpg\" alt=\"IMG_5813\" width=\"1452\" height=\"486\" srcset=\"https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_5813.jpg 1452w, https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_5813-300x100.jpg 300w, https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_5813-1024x342.jpg 1024w\" sizes=\"auto, (max-width: 1452px) 100vw, 1452px\" \/>Ich habe mir das <a href=\"http:\/\/www.sniper-as.de\/new\/index.php?c=product&amp;id=550990\" target=\"_blank\" rel=\"noopener noreferrer\">Classic Army SAR Sportmatch M41 SG<\/a> bei Sniper-AS bestellt. Es wird nach und nach immer mehr zum DMR umgebaut. Zur Zeit ist es noch eine hohle Gans.<\/p>\n<p><span style=\"text-decoration: underline;\">Zus\u00e4tzlich verbaute Teile:<\/span><br \/>\n&#8211; <a href=\"http:\/\/www.sniper-as.de\/new\/index.php?c=product&amp;id=660524od\" target=\"_blank\" rel=\"noopener noreferrer\">PTS Rail Vertical Grip<\/a><br \/>\n&#8211; <a href=\"https:\/\/www.sniper-as.de\/new\/index.php?c=product&amp;id=750134\" target=\"_blank\" rel=\"noopener noreferrer\">CA36 Side Rails<\/a><br \/>\n&#8211; <a href=\"https:\/\/www.sniper-as.de\/new\/index.php?c=product&amp;id=199207\" target=\"_blank\" rel=\"noopener noreferrer\">CA36 Long Rail<\/a><br \/>\n&#8211; <a href=\"http:\/\/www.zib-militaria.de\/epages\/61431412.sf\/de_DE\/?ObjectPath=\/Shops\/61431412\/Products\/100009\" target=\"_blank\" rel=\"noopener noreferrer\">G3 BW Einschiebbare Schulterst\u00fctze<\/a> (<a href=\"http:\/\/ripperkon.de\/original-einschiebbare-schulterstutze-fur-g3-an-ca-m41\/\">nachbearbeitet<\/a>)<br \/>\n&#8211; LLM01 Dummy (von Iceman)<br \/>\n&#8211; Systema M4 HU Unit<br \/>\n&#8211; Systema Magnum Motor<\/p>\n<p>Als Visierung benutze ich entweder <em>(siehe: oberes Bild)<\/em>:<br \/>\n&#8211;&nbsp;<a href=\"http:\/\/www.militariaandmore.de\/epages\/61636098.sf\/sec19a17f13f0\/?ObjectPath=\/Shops\/61636098\/Products\/345096543\" target=\"_blank\" rel=\"noopener noreferrer\">Hensoldt Fero Z-24<br \/>\n<\/a>&#8211;&nbsp;<a href=\"https:\/\/shop.strato.de\/epages\/61431412.sf\/sec6c03b9dd4c\/?ObjectPath=\/Shops\/61431412\/Products\/110010\" target=\"_blank\" rel=\"noopener noreferrer\">Strichplatten-Beleuchtung Hensoldt ZF\u2019s<\/a><\/p>\n<p>oder <em>(siehe: unteres Bild)<\/em>:<br \/>\n&#8211;&nbsp;<a href=\"http:\/\/www.zib-militaria.de\/epages\/61431412.sf\/de_DE\/?ObjectPath=\/Shops\/61431412\/Products\/110003\" target=\"_blank\" rel=\"noopener noreferrer\">STANAG auf Picatinny Adapter<\/a><br \/>\n&#8211;&nbsp;<a href=\"http:\/\/www.zib-militaria.de\/epages\/61431412.sf\/de_DE\/?ObjectPath=\/Shops\/61431412\/Products\/100010\" target=\"_blank\" rel=\"noopener noreferrer\">G3 BW Stanag ZF Spann-Montage<\/a><br \/>\n&#8211;&nbsp;<a href=\"http:\/\/www.sniper-as.de\/new\/index.php?c=product&amp;id=590375b\" target=\"_blank\" rel=\"noopener noreferrer\">Strike Systems Advanced Dot Sight 553<\/a><\/p>\n<p>Ich benutze <a href=\"http:\/\/www.sniper-as.de\/new\/index.php?c=product&amp;id=550323\" target=\"_blank\" rel=\"noopener noreferrer\">Classic Army G3 Low Cap Magazine<\/a>.<\/p>\n<p>Das kommt wahrscheinlich noch:<br \/>\n&#8211; G3 H\u00fclsenabweiser<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14836\" src=\"http:\/\/ripperkon.de\/wp-content\/uploads\/IMG_5815.jpg\" alt=\"IMG_5815\" width=\"1167\" height=\"778\" srcset=\"https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_5815.jpg 1167w, https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_5815-300x200.jpg 300w, https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_5815-1024x682.jpg 1024w\" sizes=\"auto, (max-width: 1167px) 100vw, 1167px\" \/><\/p>\n<p><a href=\"http:\/\/www.fine-arms.de\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" title=\"finearmsbanner\" src=\"https:\/\/ripperkon.de\/wp-content\/uploads\/finearmsbanner.gif\" alt=\"\" width=\"468\" height=\"60\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VERKAUFT, weil es mir zu viel Geld frisst und ich es zur Zeit nicht wirklich einbeziehen kann. Ich habe mir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":18654,"menu_order":0,"comment_status":"open","ping_status":"open","template":"template-full-custom.php","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-18602","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ca-g3-dmr\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ripperkon | Taktische Ausr\u00fcstung im Fokus\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Classic Army G3 DMR | Ripperkon\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ca-g3-dmr\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-05-16T20:11:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-05-16T20:11:17+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Classic Army G3 DMR | Ripperkon\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/ca-g3-dmr\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/#listItem\",\"name\":\"Tactical Lifestyle\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/#listItem\",\"position\":2,\"name\":\"Tactical Lifestyle\",\"item\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/#listItem\",\"name\":\"Airsoft-Projekte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/#listItem\",\"position\":3,\"name\":\"Airsoft-Projekte\",\"item\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/#listItem\",\"name\":\"Ehemalige Projekte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/#listItem\",\"name\":\"Tactical Lifestyle\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/#listItem\",\"position\":4,\"name\":\"Ehemalige Projekte\",\"item\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/ca-g3-dmr\\\/#listItem\",\"name\":\"Classic Army G3 DMR\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/#listItem\",\"name\":\"Airsoft-Projekte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/ca-g3-dmr\\\/#listItem\",\"position\":5,\"name\":\"Classic Army G3 DMR\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/#listItem\",\"name\":\"Ehemalige Projekte\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#organization\",\"name\":\"Ripperkon\",\"description\":\"Taktische Ausr\\u00fcstung im Fokus\",\"url\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ripperkon\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCA_0ltEzFO1OsSYo5_PA75A\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/ca-g3-dmr\\\/#webpage\",\"url\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/ca-g3-dmr\\\/\",\"name\":\"Classic Army G3 DMR | Ripperkon\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/ca-g3-dmr\\\/#breadcrumblist\"},\"datePublished\":\"2012-05-16T20:11:17+02:00\",\"dateModified\":\"2012-05-16T20:11:17+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/\",\"name\":\"Ripperkon\",\"description\":\"Taktische Ausr\\u00fcstung im Fokus\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Classic Army G3 DMR | Ripperkon","description":"","canonical_url":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ca-g3-dmr\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ca-g3-dmr\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/ripperkon.de\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/#listItem","name":"Tactical Lifestyle"}},{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/#listItem","position":2,"name":"Tactical Lifestyle","item":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/#listItem","name":"Airsoft-Projekte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/#listItem","position":3,"name":"Airsoft-Projekte","item":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/#listItem","name":"Ehemalige Projekte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/#listItem","name":"Tactical Lifestyle"}},{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/#listItem","position":4,"name":"Ehemalige Projekte","item":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ca-g3-dmr\/#listItem","name":"Classic Army G3 DMR"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/#listItem","name":"Airsoft-Projekte"}},{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ca-g3-dmr\/#listItem","position":5,"name":"Classic Army G3 DMR","previousItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/#listItem","name":"Ehemalige Projekte"}}]},{"@type":"Organization","@id":"https:\/\/ripperkon.de\/en\/#organization","name":"Ripperkon","description":"Taktische Ausr\u00fcstung im Fokus","url":"https:\/\/ripperkon.de\/en\/","sameAs":["https:\/\/www.instagram.com\/ripperkon\/","https:\/\/www.youtube.com\/channel\/UCA_0ltEzFO1OsSYo5_PA75A"]},{"@type":"WebPage","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ca-g3-dmr\/#webpage","url":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ca-g3-dmr\/","name":"Classic Army G3 DMR | Ripperkon","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ripperkon.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ca-g3-dmr\/#breadcrumblist"},"datePublished":"2012-05-16T20:11:17+02:00","dateModified":"2012-05-16T20:11:17+02:00"},{"@type":"WebSite","@id":"https:\/\/ripperkon.de\/en\/#website","url":"https:\/\/ripperkon.de\/en\/","name":"Ripperkon","description":"Taktische Ausr\u00fcstung im Fokus","inLanguage":"en-US","publisher":{"@id":"https:\/\/ripperkon.de\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ripperkon | Taktische Ausr\u00fcstung im Fokus","og:type":"article","og:title":"Classic Army G3 DMR | Ripperkon","og:url":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ca-g3-dmr\/","article:published_time":"2012-05-16T20:11:17+00:00","article:modified_time":"2012-05-16T20:11:17+00:00","twitter:card":"summary","twitter:title":"Classic Army G3 DMR | Ripperkon"},"aioseo_meta_data":{"post_id":"18602","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-11-03 19:06:35","updated":"2025-07-19 11:35:02","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ripperkon.de\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/\" title=\"Tactical Lifestyle\">Tactical Lifestyle<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/\" title=\"Airsoft-Projekte\">Airsoft-Projekte<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/\" title=\"Ehemalige Projekte\">Ehemalige Projekte<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tClassic Army G3 DMR\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ripperkon.de\/en\/"},{"label":"Tactical Lifestyle","link":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/"},{"label":"Airsoft-Projekte","link":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/"},{"label":"Ehemalige Projekte","link":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/"},{"label":"Classic Army G3 DMR","link":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ca-g3-dmr\/"}],"_links":{"self":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages\/18602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/comments?post=18602"}],"version-history":[{"count":0,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages\/18602\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages\/18654"}],"wp:attachment":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/media?parent=18602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}