{"id":18581,"date":"2012-09-20T19:37:10","date_gmt":"2012-09-20T19:37:10","guid":{"rendered":"https:\/\/ripperkon.de\/ics-mp5-sd6\/"},"modified":"2012-09-20T19:37:10","modified_gmt":"2012-09-20T19:37:10","slug":"ics-mp5-sd6","status":"publish","type":"page","link":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ics-mp5-sd6\/","title":{"rendered":"ICS MP5 SD6"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14766\" title=\"IMG_6025\" src=\"http:\/\/ripperkon.de\/wp-content\/uploads\/IMG_6025.jpg\" alt=\"\" width=\"959\" height=\"430\" srcset=\"https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_6025.jpg 959w, https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_6025-300x134.jpg 300w\" sizes=\"auto, (max-width: 959px) 100vw, 959px\" \/><\/p>\n<p>Diese ICS MP5 SD6 hat mein G36k abgel\u00f6st. Ich m\u00f6chte sie f\u00fcr OHK nutzen.<\/p>\n<p><span style=\"text-decoration: underline;\">Zus\u00e4tzlich verbaute Teile:<\/span><br \/>\nAls Visierung benutze ich entweder:<br \/>\n&#8211;&nbsp;<a href=\"http:\/\/www.militariaandmore.de\/epages\/61636098.sf\/sec19a17f13f0\/?ObjectPath=\/Shops\/61636098\/Products\/345096543\" target=\"_blank\" rel=\"noopener noreferrer\">Hensoldt Fero Z-24&nbsp;<\/a><br \/>\n&#8211;&nbsp;<a href=\"https:\/\/shop.strato.de\/epages\/61431412.sf\/sec6c03b9dd4c\/?ObjectPath=\/Shops\/61431412\/Products\/110010\" target=\"_blank\" rel=\"noopener noreferrer\">Strichplatten-Beleuchtung Hensoldt ZF\u2019s<\/a><\/p>\n<p>oder:<br \/>\n&#8211; <a href=\"http:\/\/www.zib-militaria.de\/epages\/61431412.sf\/de_DE\/?ObjectPath=\/Shops\/61431412\/Products\/110003\" target=\"_blank\" rel=\"noopener noreferrer\">STANAG auf Picatinny Adapter<\/a><br \/>\n&#8211;&nbsp;<a href=\"http:\/\/www.zib-militaria.de\/epages\/61431412.sf\/de_DE\/?ObjectPath=\/Shops\/61431412\/Products\/100010\" target=\"_blank\" rel=\"noopener noreferrer\">G3 BW Stanag ZF Spann-Montage<\/a><br \/>\n&#8211;&nbsp;<a href=\"http:\/\/www.sniper-as.de\/new\/index.php?c=product&amp;id=590375b\" target=\"_blank\" rel=\"noopener noreferrer\">Strike Systems Advanced Dot Sight 553<\/a><\/p>\n<p>Ich benutze haupts\u00e4chlich&nbsp;<a href=\"http:\/\/www.begadishop.de\/catalog\/product_info.php?manufacturers_id=&amp;products_id=4781\" target=\"_blank\" rel=\"noopener noreferrer\">BEGADI Universalmagazine vom Typ 9 (MP5, 50 Schuss, Lowcap)<\/a>.<\/p>\n<p>Das Projekt habe ich aufgegeben, weil es mich doch wieder zu einem G36k gezogen hat.<\/p>\n<p><a href=\"http:\/\/ripperkon.de\/projekte\/ics-mp5-sd6\/img_6020-kopie\/\" rel=\"attachment wp-att-2481\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14765\" title=\"IMG_6020 - Kopie\" src=\"http:\/\/ripperkon.de\/wp-content\/uploads\/IMG_6020-Kopie.jpg\" alt=\"\" width=\"1408\" height=\"875\" srcset=\"https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_6020-Kopie.jpg 1408w, https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_6020-Kopie-300x186.jpg 300w, https:\/\/ripperkon.de\/wp-content\/uploads\/IMG_6020-Kopie-1024x636.jpg 1024w\" sizes=\"auto, (max-width: 1408px) 100vw, 1408px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diese ICS MP5 SD6 hat mein G36k abgel\u00f6st. Ich m\u00f6chte sie f\u00fcr OHK nutzen. Zus\u00e4tzlich verbaute Teile: Als Visierung benutze [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":18654,"menu_order":0,"comment_status":"open","ping_status":"open","template":"template-full-custom.php","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-18581","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ics-mp5-sd6\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ripperkon | Taktische Ausr\u00fcstung im Fokus\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"ICS MP5 SD6 | Ripperkon\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ics-mp5-sd6\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-09-20T19:37:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-09-20T19:37:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"ICS MP5 SD6 | Ripperkon\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/ics-mp5-sd6\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/#listItem\",\"name\":\"Tactical Lifestyle\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/#listItem\",\"position\":2,\"name\":\"Tactical Lifestyle\",\"item\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/#listItem\",\"name\":\"Airsoft-Projekte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/#listItem\",\"position\":3,\"name\":\"Airsoft-Projekte\",\"item\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/#listItem\",\"name\":\"Ehemalige Projekte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/#listItem\",\"name\":\"Tactical Lifestyle\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/#listItem\",\"position\":4,\"name\":\"Ehemalige Projekte\",\"item\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/ics-mp5-sd6\\\/#listItem\",\"name\":\"ICS MP5 SD6\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/#listItem\",\"name\":\"Airsoft-Projekte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/ics-mp5-sd6\\\/#listItem\",\"position\":5,\"name\":\"ICS MP5 SD6\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/#listItem\",\"name\":\"Ehemalige Projekte\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#organization\",\"name\":\"Ripperkon\",\"description\":\"Taktische Ausr\\u00fcstung im Fokus\",\"url\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ripperkon\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCA_0ltEzFO1OsSYo5_PA75A\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/ics-mp5-sd6\\\/#webpage\",\"url\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/ics-mp5-sd6\\\/\",\"name\":\"ICS MP5 SD6 | Ripperkon\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/tactical-lifestyle\\\/projekte\\\/ehemalige\\\/ics-mp5-sd6\\\/#breadcrumblist\"},\"datePublished\":\"2012-09-20T19:37:10+02:00\",\"dateModified\":\"2012-09-20T19:37:10+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/\",\"name\":\"Ripperkon\",\"description\":\"Taktische Ausr\\u00fcstung im Fokus\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"ICS MP5 SD6 | Ripperkon","description":"","canonical_url":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ics-mp5-sd6\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ics-mp5-sd6\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/ripperkon.de\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/#listItem","name":"Tactical Lifestyle"}},{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/#listItem","position":2,"name":"Tactical Lifestyle","item":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/#listItem","name":"Airsoft-Projekte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/#listItem","position":3,"name":"Airsoft-Projekte","item":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/#listItem","name":"Ehemalige Projekte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/#listItem","name":"Tactical Lifestyle"}},{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/#listItem","position":4,"name":"Ehemalige Projekte","item":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ics-mp5-sd6\/#listItem","name":"ICS MP5 SD6"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/#listItem","name":"Airsoft-Projekte"}},{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ics-mp5-sd6\/#listItem","position":5,"name":"ICS MP5 SD6","previousItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/#listItem","name":"Ehemalige Projekte"}}]},{"@type":"Organization","@id":"https:\/\/ripperkon.de\/en\/#organization","name":"Ripperkon","description":"Taktische Ausr\u00fcstung im Fokus","url":"https:\/\/ripperkon.de\/en\/","sameAs":["https:\/\/www.instagram.com\/ripperkon\/","https:\/\/www.youtube.com\/channel\/UCA_0ltEzFO1OsSYo5_PA75A"]},{"@type":"WebPage","@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ics-mp5-sd6\/#webpage","url":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ics-mp5-sd6\/","name":"ICS MP5 SD6 | Ripperkon","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ripperkon.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ics-mp5-sd6\/#breadcrumblist"},"datePublished":"2012-09-20T19:37:10+02:00","dateModified":"2012-09-20T19:37:10+02:00"},{"@type":"WebSite","@id":"https:\/\/ripperkon.de\/en\/#website","url":"https:\/\/ripperkon.de\/en\/","name":"Ripperkon","description":"Taktische Ausr\u00fcstung im Fokus","inLanguage":"en-US","publisher":{"@id":"https:\/\/ripperkon.de\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ripperkon | Taktische Ausr\u00fcstung im Fokus","og:type":"article","og:title":"ICS MP5 SD6 | Ripperkon","og:url":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ics-mp5-sd6\/","article:published_time":"2012-09-20T19:37:10+00:00","article:modified_time":"2012-09-20T19:37:10+00:00","twitter:card":"summary","twitter:title":"ICS MP5 SD6 | Ripperkon"},"aioseo_meta_data":{"post_id":"18581","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-11-03 19:10:41","updated":"2025-07-19 11:36:02","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ripperkon.de\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/\" title=\"Tactical Lifestyle\">Tactical Lifestyle<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/\" title=\"Airsoft-Projekte\">Airsoft-Projekte<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/\" title=\"Ehemalige Projekte\">Ehemalige Projekte<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tICS MP5 SD6\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ripperkon.de\/en\/"},{"label":"Tactical Lifestyle","link":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/"},{"label":"Airsoft-Projekte","link":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/"},{"label":"Ehemalige Projekte","link":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/"},{"label":"ICS MP5 SD6","link":"https:\/\/ripperkon.de\/en\/tactical-lifestyle\/projekte\/ehemalige\/ics-mp5-sd6\/"}],"_links":{"self":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages\/18581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/comments?post=18581"}],"version-history":[{"count":0,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages\/18581\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages\/18654"}],"wp:attachment":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/media?parent=18581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}