{"id":17961,"date":"2019-10-06T15:24:22","date_gmt":"2019-10-06T13:24:22","guid":{"rendered":"https:\/\/ripperkon.de\/sonstige\/best-sniper-2019\/"},"modified":"2021-11-03T19:56:54","modified_gmt":"2021-11-03T18:56:54","slug":"best-sniper-2019","status":"publish","type":"page","link":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/best-sniper-2019\/","title":{"rendered":"Best Sniper 2019"},"content":{"rendered":"<p>Ein Wettkampf von <a href=\"https:\/\/asso-sion.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\">Asso-Sion<\/a> in der Schweiz. Mit vielen Elementen aus dem Scharfsch\u00fctzenwesen, Survival und Milit\u00e4r.<br \/>\nIch habe auch einen kleinen Beitrag zum Event geschrieben. Diesen findest du hier: <a href=\"http:\/\/ripperkon.de\/best-sniper-2019-schweiz-suisse\/\">Best Sniper 2019 &#8211; Schweiz \/ Suisse<\/a><\/p>\n<p>ngg_shortcode_0_placeholder<div class=\"cta-element\"><h4 class=\"cta-small-title\">L\u2019association des sous-officiers de Sion et environs<\/h4><h2 class=\"cta-title\">Asso Sion<\/h2><a class=\"button\" href=\"https:\/\/asso-sion.ch\/\" target=\"_blank\">Zur Webseite<\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Wettkampf von Asso-Sion in der Schweiz. Mit vielen Elementen aus dem Scharfsch\u00fctzenwesen, Survival und Milit\u00e4r. Ich habe auch einen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":17946,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-full-custom.php","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-17961","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ripperkon.de\/en\/photography\/sonstige\/best-sniper-2019\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ripperkon | Taktische Ausr\u00fcstung im Fokus\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Best Sniper 2019 | Ripperkon\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ripperkon.de\/en\/photography\/sonstige\/best-sniper-2019\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-10-06T13:24:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-11-03T18:56:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Best Sniper 2019 | Ripperkon\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/sonstige\\\/best-sniper-2019\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/#listItem\",\"name\":\"Photography\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/#listItem\",\"position\":2,\"name\":\"Photography\",\"item\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/sonstige\\\/#listItem\",\"name\":\"Sonstige\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/sonstige\\\/#listItem\",\"position\":3,\"name\":\"Sonstige\",\"item\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/sonstige\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/sonstige\\\/best-sniper-2019\\\/#listItem\",\"name\":\"Best Sniper 2019\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/#listItem\",\"name\":\"Photography\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/sonstige\\\/best-sniper-2019\\\/#listItem\",\"position\":4,\"name\":\"Best Sniper 2019\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/sonstige\\\/#listItem\",\"name\":\"Sonstige\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#organization\",\"name\":\"Ripperkon\",\"description\":\"Taktische Ausr\\u00fcstung im Fokus\",\"url\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ripperkon\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCA_0ltEzFO1OsSYo5_PA75A\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/sonstige\\\/best-sniper-2019\\\/#webpage\",\"url\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/sonstige\\\/best-sniper-2019\\\/\",\"name\":\"Best Sniper 2019 | Ripperkon\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/photography\\\/sonstige\\\/best-sniper-2019\\\/#breadcrumblist\"},\"datePublished\":\"2019-10-06T15:24:22+02:00\",\"dateModified\":\"2021-11-03T19:56:54+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/\",\"name\":\"Ripperkon\",\"description\":\"Taktische Ausr\\u00fcstung im Fokus\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ripperkon.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Best Sniper 2019 | Ripperkon","description":"","canonical_url":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/best-sniper-2019\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/best-sniper-2019\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/ripperkon.de\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/photography\/#listItem","name":"Photography"}},{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/photography\/#listItem","position":2,"name":"Photography","item":"https:\/\/ripperkon.de\/en\/photography\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/#listItem","name":"Sonstige"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/#listItem","position":3,"name":"Sonstige","item":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/best-sniper-2019\/#listItem","name":"Best Sniper 2019"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/photography\/#listItem","name":"Photography"}},{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/best-sniper-2019\/#listItem","position":4,"name":"Best Sniper 2019","previousItem":{"@type":"ListItem","@id":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/#listItem","name":"Sonstige"}}]},{"@type":"Organization","@id":"https:\/\/ripperkon.de\/en\/#organization","name":"Ripperkon","description":"Taktische Ausr\u00fcstung im Fokus","url":"https:\/\/ripperkon.de\/en\/","sameAs":["https:\/\/www.instagram.com\/ripperkon\/","https:\/\/www.youtube.com\/channel\/UCA_0ltEzFO1OsSYo5_PA75A"]},{"@type":"WebPage","@id":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/best-sniper-2019\/#webpage","url":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/best-sniper-2019\/","name":"Best Sniper 2019 | Ripperkon","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ripperkon.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/best-sniper-2019\/#breadcrumblist"},"datePublished":"2019-10-06T15:24:22+02:00","dateModified":"2021-11-03T19:56:54+01:00"},{"@type":"WebSite","@id":"https:\/\/ripperkon.de\/en\/#website","url":"https:\/\/ripperkon.de\/en\/","name":"Ripperkon","description":"Taktische Ausr\u00fcstung im Fokus","inLanguage":"en-US","publisher":{"@id":"https:\/\/ripperkon.de\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Ripperkon | Taktische Ausr\u00fcstung im Fokus","og:type":"article","og:title":"Best Sniper 2019 | Ripperkon","og:url":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/best-sniper-2019\/","article:published_time":"2019-10-06T13:24:22+00:00","article:modified_time":"2021-11-03T18:56:54+00:00","twitter:card":"summary","twitter:title":"Best Sniper 2019 | Ripperkon"},"aioseo_meta_data":{"post_id":"17961","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-11-03 18:42:53","updated":"2025-07-19 11:51:44","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ripperkon.de\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ripperkon.de\/en\/photography\/\" title=\"Photography\">Photography<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ripperkon.de\/en\/photography\/sonstige\/\" title=\"Sonstige\">Sonstige<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBest Sniper 2019\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ripperkon.de\/en\/"},{"label":"Photography","link":"https:\/\/ripperkon.de\/en\/photography\/"},{"label":"Sonstige","link":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/"},{"label":"Best Sniper 2019","link":"https:\/\/ripperkon.de\/en\/photography\/sonstige\/best-sniper-2019\/"}],"_links":{"self":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages\/17961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/comments?post=17961"}],"version-history":[{"count":1,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages\/17961\/revisions"}],"predecessor-version":[{"id":18044,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages\/17961\/revisions\/18044"}],"up":[{"embeddable":true,"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/pages\/17946"}],"wp:attachment":[{"href":"https:\/\/ripperkon.de\/en\/wp-json\/wp\/v2\/media?parent=17961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}